{"id":2,"count":10,"description":"","link":"https:\/\/matchdatelove.com\/index.php\/category\/eco-travel\/","name":"eco travel","slug":"eco-travel","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/matchdatelove.com\/index.php\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matchdatelove.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/matchdatelove.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/matchdatelove.com\/index.php\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}